












{"id":310,"date":"2017-06-28T11:43:41","date_gmt":"2017-06-28T09:43:41","guid":{"rendered":"http:\/\/www.adventuretrekking-nepal.com\/?p=310"},"modified":"2017-07-07T07:06:49","modified_gmt":"2017-07-07T05:06:49","slug":"pisang-peak-climbing-with-thorong-la-pass","status":"publish","type":"post","link":"http:\/\/www.adventuretrekking-nepal.com\/de\/pisang-peak-climbing-with-thorong-la-pass\/","title":{"rendered":"Pisang Gipfelbesteigung mit Thorong La Pass"},"content":{"rendered":"<h3>Informationen zur Tour<\/h3>\n<p>Die Pisang Gipfelbesteigung beinhaltet ein Trekking in der ber\u00fchmten Annapurna Region und dem Gipfel Pisang Peak. Dar\u00fcber hinaus besuchen wir Muktinath und wandern in der wundersch\u00f6nen Region Manang von Nepal. Unsere 18-t\u00e4gige Reise beginnt in Kathmandu, wo wir unsere Kletterguide \/ Guide und Mitkletterer treffen. Wir fahren am n\u00e4chsten Tag nach Dharapani und beginnen von dort zu wandern. Wir genie\u00dfen die Aussicht auf Annapurna, Tilicho und Gangapurna auf unserem Trek zum Pisang Peak und Gipfel der Spitze am neunten Tag unserer Reise. Die Aussicht auf die Annapurna Ranges, Dhaulagiri und andere Himalaya von oben sind gro\u00dfartig. Auf dem R\u00fcckweg folgen wir dem Weg, der uns f\u00fchrt, um Muktinath zu \u00fcberqueren, der ein wichtiger Wallfahrtsort f\u00fcr nepalesische Menschen ist. Wir \u00fcberqueren den Thorong La Pass, der h\u00f6chste Bergpass der Welt, um Muktinath zu erreichen. Unsere Pisang Peak Reiseplan beinhaltet auch die sch\u00f6ne Jomsom Region, die eine lohnende Erfahrung sein wird. Von Jomsom fliegen wir nach Pokhara und fahren von dort nach Kathmandu und beenden unsere erstaunliche Reise in Nepal.<\/p>\n<p class=\"br\">&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td>Gruppengr\u00f6\u00dfe:<\/td>\n<td>Minimum 2 Personen<\/td>\n<\/tr>\n<tr>\n<td>Max-H\u00f6he:<\/td>\n<td>6,091m\/19,980ft<\/td>\n<\/tr>\n<tr>\n<td>Reiseziel:<\/td>\n<td>Nepal<\/td>\n<\/tr>\n<tr>\n<td>Ankunft in:<\/td>\n<td>Kathmandu, Nepal<\/td>\n<\/tr>\n<tr>\n<td>Abfahrt von:<\/td>\n<td>Kathmandu, Nepal<\/td>\n<\/tr>\n<tr>\n<td>Mahlzeiten:<\/td>\n<td>Alle Mahlzeiten beim Trekking und Klettern. Fr\u00fchst\u00fcck in Kathmandu und Pokhara<\/td>\n<\/tr>\n<tr>\n<td>Unterkunft:<\/td>\n<td>Hotels. Teeh\u00e4user w\u00e4hrend der Wanderung und Zelte beim Camping<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\"br\">&nbsp;<\/p>\n<a id=\"opener-unter1\" class=\"opener\" href=\"javascript:mj_toggle_section('unter1')\">Empfohlene Ausr\u00fcstung<\/a>\n<div id='section-unter1' class='section clearfix'>\n<h4>Ausr\u00fcstungen &amp;\u00a0Packliste<\/h4>\n<p>Diese Liste ist ein Leitfaden, um Ihnen zu helfen, f\u00fcr das Trekking und Peak-Klettern zu packen. Bitte verstehen Sie, dass die unten aufgef\u00fchrten Gegenst\u00e4nde ein wenig nach der Saison und der Trek-Dauer variieren. Die mit einem Sternchen (*) gekennzeichneten Gegenst\u00e4nde werden von Pinnacle Trek zur Verf\u00fcgung gestellt und sind im Service inklusive. Denken Sie daran, dass Ihr Gep\u00e4ck von Ihrem Portier getragen wird, aber Sie sind verpflichtet, einen Tagesrucksack (mit Ihren Wertsachen oder etwas Wichtiges) auf eigene Faust zu tragen. Wir schlagen auch vor, dass du nur das n\u00f6tige packst.<\/p>\n<h4>Wichtige Dokumente und Artikel<\/h4>\n<ul>\n<li>G\u00fcltiger Reisepass<\/li>\n<li>2 zus\u00e4tzliche Passfotos<\/li>\n<li>Flugtickets<\/li>\n<li>Separate Fotokopien des Passes<\/li>\n<li>Visa Formular (leicht erreichbar am Flughafen Kathmandu)<\/li>\n<li>Versicherungsnachweis<\/li>\n<li>Dollars in bar f\u00fcr den Kauf des nepalesischen Visums am Flughafen Kathmandu<\/li>\n<li>Kreditkarten, EC-Karte, f\u00fcr die Abhebung von Geldern aus Geldautomaten (bringen Sie eine Fotokopie Ihrer Karten mit)\u00a0<\/li>\n<\/ul>\n<h4>Pers\u00f6nliche Kletter Gegenst\u00e4nde:<\/h4>\n<ul>\n<li>Eispickel<\/li>\n<li>Steigeisen<\/li>\n<li>Harness<\/li>\n<li>Bandschlingen (2)<\/li>\n<li>Schraubkarabiner (2 Schloss, 2 Entriegelung)<\/li>\n<li>Abseilachter<\/li>\n<li>Kunststoff-Bergschuhe<\/li>\n<li>Steigklemme \/ Jumar<\/li>\n<li>Helm<\/li>\n<\/ul>\n<h4>Gruppen Kletter Gegenst\u00e4nge:<\/h4>\n<ul>\n<li>Schneestange*<\/li>\n<li>Seil*<\/li>\n<li>Eishammer *<\/li>\n<li>Eisschraube *<\/li>\n<\/ul>\n<p><strong>Kopf<\/strong><\/p>\n<ul>\n<li>Bandana oder Kopf Schal, auch n\u00fctzlich f\u00fcr staubige Bedingungen<\/li>\n<li>Warmer Hut, der Ihre Ohren bedeckt (Wolle oder Synthetik)<\/li>\n<li>Scheinwerfer mit zus\u00e4tzlichen Batterien und Gl\u00fchlampen<\/li>\n<li>Sonnenbrille mit UV-Schutz<\/li>\n<li>Verschreibungspflichtige Sonnenbrille (falls erforderlich)\u00a0<\/li>\n<\/ul>\n<p><strong>Oberk\u00f6rper<\/strong><\/p>\n<ul>\n<li>Polypropylenhemden (1 kurze \u00c4rmel und 2 lange \u00c4rmel)<\/li>\n<li>Leicht- und Expeditionsgewichts-Thermo-Tops<\/li>\n<li>Fleece-Wind-Stop-Jacke oder Pullover<\/li>\n<li>Wasserdichte Manteljacke (vorzugsweise atmungsaktive Stoffe)<\/li>\n<li>Daunenweste und \/ oder Jacke<\/li>\n<li>Gore-Tex Jacke mit Kapuze, wasserdicht und atmungsaktiv\u00a0<\/li>\n<\/ul>\n<p><strong>H\u00e4nde<\/strong><\/p>\n<ul>\n<li>1 Paar leichte Poly-Liner-Handschuhe<\/li>\n<li>1 Paar leichte Wolle oder Fleece-Handschuhe<\/li>\n<li>1 Paar Handschuhe; Bestehend aus: 1 Gore-Tex \u00dcberhandschuh mit abgestimmten, wasserdichten Polar-Fleece Innenhandschuh \u00a0<\/li>\n<\/ul>\n<p><strong>Unterk\u00f6rper<\/strong><\/p>\n<ul>\n<li>Nicht-Baumwoll-Unterw\u00e4sche-Slips<\/li>\n<li>1 Paar Wanderhosen<\/li>\n<li>1 Paar Wanderhose<\/li>\n<li>1 Paar leichte thermische Hosen<\/li>\n<li>1 Paar Vlies oder Wollhose<\/li>\n<li>1 Paar wasserdichte Schalenhose, atmungsaktives Gewebe<\/li>\n<\/ul>\n<p><strong>F\u00fc\u00dfe<\/strong><\/p>\n<ul>\n<li>2 Paar d\u00fcnne, leichte Innensocken<\/li>\n<li>2 Paar schwere Poly- oder Wollsocken<\/li>\n<li>1 Paar Wanderschuhe mit Ersatzschn\u00fcrsenkel (stabile Sohlen, wasserdicht, Kn\u00f6chelunterst\u00fctzung, \u201egebrochen\u201c)<\/li>\n<li>1 Paar Trainer oder Laufschuhe und \/ oder Sandalen<\/li>\n<li>Baumwollsocken<\/li>\n<li>Gamaschen\u00a0<\/li>\n<\/ul>\n<p><strong>Schlafen<\/strong><\/p>\n<ul>\n<li>1 Schlafsack 30 Grad DC<\/li>\n<li>Fleece Innenschlafsack\u00a0<\/li>\n<\/ul>\n<p><strong>Rucksack and Travel Bags<\/strong><\/p>\n<ul>\n<li>1 mittlerer Rucksack oder 1 gro\u00dfe Reisetasche *<\/li>\n<li>Daypack \/ Rucksack von 35 bis 50 Liter zum Tragen Ihrer Wertsachen, sollte eine gute Schulterpolsterung haben<\/li>\n<li>Kleine Vorh\u00e4ngeschl\u00f6sser f\u00fcr Sporttasche<\/li>\n<li>2 gro\u00dfe wasserdichte Rucksackbez\u00fcge (optional)\u00a0<\/li>\n<\/ul>\n<p><strong>Medizin<\/strong><\/p>\n<ul>\n<li>Kleiner, pers\u00f6nlicher Erste-Hilfe-Kasten (einfach und leicht)<\/li>\n<li>Aspirin, Fixierbinde und Pflaster (Pflaster)<\/li>\n<li>1\u00a0Erste Hilfe Set f\u00fcr Haut-Blasen<\/li>\n<li>Anti-Durchfall Tabletten<\/li>\n<li>Anti-Kopfschmerzen Tabletten<\/li>\n<li>Grippetabletten<\/li>\n<li>Anti-H\u00f6hen-Krankheit Pillen: Diamox oder Acetylzolamid<\/li>\n<li>Magen-Antibiotikum: Ciprofloxacin, etc. Hinweis: Bringen Sie keine Schlaftabletten mit!<\/li>\n<li>Wasserreinigungstabletten oder Wasserfilter<\/li>\n<li>1 Satz Ohrst\u00f6psel<\/li>\n<li>Extra-Brillengl\u00e4ser, Kontaktlinsen-Verbrauchsmaterialien<\/li>\n<\/ul>\n<p><strong>Praktische Utensilien<\/strong><\/p>\n<ul>\n<li>1 kleine Rolle Reparaturband, 1 N\u00e4h-Reparatur-Kit<\/li>\n<li>1 Feuerzeug, 1 kleine Schachtel mit Streichh\u00f6lzern<\/li>\n<li>1 Kompass oder GPS (optional)<\/li>\n<li>1 Wecker \/ Uhr<\/li>\n<li>1 Digitalkamera mit zus\u00e4tzlichen Karten und Batterien<\/li>\n<li>Gro\u00dfe Zip-Verschlu\u00dfbeutel<\/li>\n<li>2 Wasserflaschen (je 1 Liter)<\/li>\n<li>1 kleines Klappmesser<\/li>\n<li>Fernglas (optional)<\/li>\n<li>4 gro\u00dfe, wasserdichte, wegwerfbare M\u00fclls\u00e4cke\u00a0<\/li>\n<\/ul>\n<p><strong>Toiletartikel<\/strong><\/p>\n<ul>\n<li>1 mittelgro\u00dfes schnell trocknendes Handtuch<\/li>\n<li>Zahnb\u00fcrste \/ Paste (vorzugsweise biologisch abbaubar)<\/li>\n<li>Mehrzweckseife (vorzugsweise biologisch abbaubar)<\/li>\n<li>Deodorants<\/li>\n<li>Nagelknipser<\/li>\n<li>Gesicht und K\u00f6rper Feuchtigkeitscreme<\/li>\n<li>Weibliche Hygieneprodukte<\/li>\n<li>Kleiner Spiegel<\/li>\n<\/ul>\n<p><strong>Pers\u00f6nliche Hygiene<\/strong><\/p>\n<ul>\n<li>Nasswischt\u00fccher (Babyt\u00fccher)<\/li>\n<li>Toilettenpapier<\/li>\n<li>Anti-bakterielle Handseife\u00a0<\/li>\n<\/ul>\n<p><strong>Extras\/Luxus<\/strong><\/p>\n<ul>\n<li>Buch<\/li>\n<li>Landkarte \/ Reisef\u00fchrer<\/li>\n<li>Zeitschrift und Stift<\/li>\n<li>IPod<\/li>\n<li>Reisespiel zB Schach, Backgammon, Scrabble, Spielkarten (um Ihnen zu helfen, die Zeit in Teeh\u00e4usern und \/ oder Lagern zu vertreiben)<\/li>\n<li>1 bescheidener Badeanzug<\/li>\n<li>Fernglas (optional)<\/li>\n<li>Spannungswandler (von 220 bis 110 Ampere)<\/li>\n<li>Steckeradapter (2 Rundzapfen zu 2 flachen Stiften)<\/li>\n<li>Leichter Kissenbezug (falls Teeh\u00e4user Ihnen Kissen zur Verf\u00fcgung stellen) oder dein eigenes Kissen<\/li>\n<\/ul>\n<\/div>\n<a id=\"opener-unter2\" class=\"opener\" href=\"javascript:mj_toggle_section('unter2')\">Tourplan<\/a>\n<div id='section-unter2' class='section clearfix'>\n<p><strong>Tag 01: Ankunft in Kathmandu (1.350m \/ 4.428ft)<\/strong><br \/>\n Wir vervollst\u00e4ndigen unsere Zollformalit\u00e4ten am Tribhuwan International Airport in Kathmandu. Danach wartet ein Pinnacle treks Mitarbeiter auf uns, der uns zu unserem Hotel bringen wird. Wir k\u00f6nnen dann den Rest des Tages frei verbringen. Am Abend probieren wir nepalesische K\u00fcche zu einem Willkommens Abendessen, das von Pinnacle Treks veranstaltet wird. \u00dcbernachtung in Kathmandu.<br \/>\n Inbegriffene Mahlzeiten: Abendessen<\/p>\n<p><strong>Tag 02: Kathmandu (1300m \/ 4264ft): Reisevorbereitung<\/strong><br \/>\n Heute Nachmittag besichtigen wir das Pinnacle Treks B\u00fcro. Im B\u00fcro treffen wir auf unsere Kletterguides und weitere Kletterer. Unser Guide wird unsere Ausr\u00fcstung \u00fcberpr\u00fcfen, um sicherzustellen, dass sie in einem perfekten Zustand f\u00fcr die kommende Reise ist. In der kurzen Besprechung werden uns die Pinnacle Treks Mitarbeiter auch helfen, zu verstehen, was uns w\u00e4hrend der Reise erwartet und um uns mit unserer Wanderung vertraut zu machen. Wir k\u00f6nnen den Rest des Nachmittags ausruhen und \/ oder in der Freizeit verbringen. \u00dcbernachtung in Kathmandu.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck<\/p>\n<p><strong>Tag 03: Fahrt von Kathmandu nach Dharapani (1.960m): 11-12 Stunden<\/strong><br \/>\n Nach dem Fr\u00fchst\u00fcck beginnen wir mit unserer Fahrt nach Dharapani. Es ist eine lange Reise \u00fcber sch\u00f6ne nepalesische Gemeinden. Am Beginn unserer Reise \u00fchrt uns der Weg neben dem kurvenreichen Trishuli River. Wir passieren auch Pokhara, im Volksmund bekannt als die Lake City vor dem Erreichen Dharapani, die eines der gr\u00f6\u00dften D\u00f6rfer im Manang-Tal ist. \u00dcbernachtung in Dharapani.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 04: Dharapani zu Chame (2.710m): 5 &#8211; 6 Stunden<\/strong><br \/>\n Auf dem Weg nach Chame passieren wir heute ein paar steile Stellen, bewaldete Bergr\u00fccken zusammen mit mehreren Erdrutschen. Wir sollten nicht vergessen, dass wir mit den bemerkenswerten Ansichten von Lamjung Himal, Annapurna II und Annapurna IV (7.525m) begr\u00fc\u00dft werden. Wir kommen auch auf kleine hei\u00dfe Quellen, die uns helfen, f\u00fcr eine Weile zu entspannen. \u00dcbernachtung in Chame.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 05: Chame zum Oberen Pisang (3.700m \/ 12.136ft): 5-6 Stunden<\/strong><br \/>\n Ein schmaler steiler Pfad durch einen sehr dichten Pinienwald f\u00fchrt uns zu einer dramatischen, geschwungenen Felswand, die 1500m vom Fluss entfernt liegt. Als der Weg sich \u00f6ffnet, werden wir von Himalaya-Gipfeln bis nach Pisang umgeben sein. Wir steigen drei\u00dfig Minuten zu einem gro\u00dfen H\u00fcgel hinauf, um Oberpisang zu erreichen. \u00dcbernachtung im Oberen Pisang.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 06: Akklimatisierung<\/strong><br \/>\n Heute ist f\u00fcr der Tag allein f\u00fcr die Akklimatisierung vorgesehen. Die Verl\u00e4ngerung in einer H\u00f6henlage garantiert, dass wir eine erfolgreiche Reise haben. Wir verbringen den ganzen Tag und erkunden das Dorf. Die Erkundung des Dorfes und die Interaktion mit den Einheimischen wird uns helfen, einen besseren Einblick in den lokalen Lebensstil zu bekommen. W\u00e4hrend des ganzen Tages sind die Ansichten von Annapurna, Gangapurna und Tilicho zu bewundern. \u00dcbernachtung im Oberen Pisang.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 07: Oberes Pisang zum Pisang Peak Base Camp (4.380m \/ 14.370ft): 4-5 Stunden<\/strong><br \/>\n Nach dem Fr\u00fchst\u00fcck beginnen wir unsere Wanderung in Richtung Pisang Base Camp. Wir steigen auf eine Spur, die durch einen d\u00fcnnen Wald und Wiesen f\u00fchrt. Die Weide wird zum Weiden von Yaks verwendet und ist auch der beste Platz, um unser Lager zu gr\u00fcnden. Der Boden ist flach und f\u00e4llt auf einen frequentierten Weg. \u00dcbernachtung im Pisang Peak Base Camp.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 08: Pisang Peak Base Camp zum Hochlager (5.400m \/ 17.712ft): 3-4 Stunden<\/strong><br \/>\n Wir steigen auf den S\u00fcd-Westkamm und erreichen das hohe Lager. Nach der Einrichtung unseres Camps nehmen wir an einem grundlegenden Klettertraining teil. Unsere Guides werden uns Schulungen f\u00fcr Spitzenklettertechniken und die richtige Art und Weise der Verwendung von Kletterger\u00e4ten wie die Eispickel, Kletterstiefel und Steigeisen, Kabelbaum, Ascender usw. bieten. Das Training beinhaltet auch die Verwendung von Seilen nach oben und unten. Obwohl es nicht zwingend notwendig ist, eine vorherige Ausbildung f\u00fcr Pisang Peak-Klettern zu haben, glauben wir stark, dass einige Trainingserfahrungen Ihr Vertrauen und Ihre Kletterf\u00e4higkeiten steigern, um die Chancen zu erh\u00f6hen, den Gipfel zu skalieren und die Erfahrung voll zu genie\u00dfen. \u00dcbernachtung im Pisang Peak High Camp.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 09: Gipfel Pisang Peak und zur\u00fcck zum Basislager (6.091m \/ 19.980ft): 8-9 Stunden<\/strong><br \/>\n Fr\u00fch am Morgen, nach dem Fr\u00fchst\u00fcck, beginnen wir unsere Wanderung. Der heutige Weg wird meistens auf felsigen Fl\u00e4chen liegen. Der Gipfel ist steil; Daher gibt es nicht viel Schnee. Wir ben\u00f6tigen rund 20m Seil, um auf einem Grat zu klettern. Rund um den Gipfel ist ein etwa 70 Grad Hang, die die Nutzung von rund 200m Seil erfordert. Sowohl Fixseil als auch andere Seil werden verwendet. Die Ansichten der Annapurna und andere Gipfeln ist au\u00dfergew\u00f6hnlich. Wir kehren zum Basislager f\u00fcr eine \u00dcbernachtung zur\u00fcck.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 10: Kontingenz<\/strong><br \/>\n Dies ist ein separater Tag f\u00fcr jede Kontingenz vorbehalten. Wenn wir nicht in der Lage sind, den Pisang-Gipfel am Tag wie geplant, wegen schlechtem Wetters oder eines unvorhergesehenen Ereignisses zu besichtigen, kann dieser Tag verwendet werden.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 11: Pisang Peak Base Camp nach Manang Valley (3.450m \/ 11.316ft): 5-6 Stunden<\/strong><br \/>\n Aus dem Basislager des Pisang-Gipfels wandern wir in Richtung Pisang Dorf. Von Pisang gibt es zwei Wege nach Manang. Wir w\u00e4hlen denjenigen, der \u00fcber den Oberen Pisang \u00fcber Geru f\u00fchrt, da dieser eine hervorragende Aussicht auf den Berg bietet. Annapurna, Pisang Peak und andere. Als wir in der N\u00e4he von Manang wandern, wird das Klima kalt und trocken. Doch ein kurzer Besuch im Barge Kloster, das gr\u00f6\u00dfte Kloster im Bezirk Manang sollte uns aufmuntern. \u00dcbernachtung in Manang.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 12: Manang zu Yak Kharka (4,110m \/ 13.484ft): 3 &#8211; 4 Stunden<\/strong><\/p>\n<p>Von Manang Dorf weg kreuzt der Weg einen Strom, klettert in das Dorf Tenki \u00fcber Manang und dann weiter aus dem Marshyangdi Tal in das nordwestliche Tal von Jarsang Khola. Der Weg folgt diesem Tal nordw\u00e4rts, vorbei an ein paar Weiden, ein Schatz von Wacholderb\u00e4umen. Der Weg f\u00fchrt weiter in die N\u00e4he des kleinen Dorfes Ghunsa, einer Gruppe von flachen Schlammd\u00e4chern knapp unterhalb des Trailhead. Jetzt geht der Weg durch Wiesen, wo Pferde und Yaks weiden. Nach dem \u00dcberqueren eines kleinen Flusses auf einer Holzbr\u00fccke f\u00fchrt der Weg an einer alten Mani-Mauer in eine angenehme Wiese und erreicht dann ein weiteres kleines Dorf namens Yak Kharka. Kleiner, aber allm\u00e4hlicher Aufstieg ist der Schl\u00fcssel zur Vermeidung von H\u00f6henproblemen.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 13: Yak kharka nach Thorang Phedi: (4420m \/ 14501ft): 3-4 Stunden<\/strong><br \/>\n Es ist ein bergauf Marsch zu Thorang Phedi. Nach einiger Zeit \u00fcberqueren wir eine H\u00e4ngebr\u00fccke und erreichen das Dorf Ledar. Wir steigen weiter hinauf und gehen durch hoch aufragende Klippen, bevor wir Thorang Phedi erreichen, das letzte Dorf vor Thorong La. Auf dieser Reise werden wir mit einer der besten Aussichten von Mt. belohnt. Gundang, Mt. Syagang, Thorung Peak und Mt. Khatungkan \u00dcbernachtung in Thorang Phedi.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 14: Thorang Phedi nach Thorong La (5416m \/ 17764ft), weiter Trek nach Muktinath (3.800 \/ 12.467ft): 9-10 Stunden<\/strong><br \/>\n Die \u00dcberquerung vom Thorong La Pass, einer der h\u00f6chsten P\u00e4sse der Welt wird heute unser oberstes Ziel sein. Wir werden den Pass vom Osten nach Westen \u00fcberqueren (Manang nach Muktinath), der die einfachste und sicherste Route ist. Wir stehen um drei Uhr morgens auf und gehen den Berg hinauf. Wenn wir es endlich an die Spitze bringen, ist uns klar, dass unsere Reise es wert war. Wir k\u00f6nnen ein paar Fotos machen, bevor wir zum Muktinath Valley am Fu\u00dfe des Thorong La Passes gehen. Wir wandern weiter nach Muktinath, was ein wichtiger Wallfahrtsort f\u00fcr Hindus und Buddhisten ist. \u00dcbernachtung in Muktinath.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 15: Muktinath zu Jomsom (2.715m \/ 8.910ft): 5-6 Stunden<\/strong><br \/>\n Muktinath ist ein wichtiger Wallfahrtsort f\u00fcr Buddhisten und Hindus. Am Morgen besuchen wir den Tempel und ein buddhistisches Kloster in der N\u00e4he des Tempels. Nach der kurzen Tour fahren wir weiter nach Jomsom, das f\u00fcr seine s\u00fc\u00dfen \u00c4pfel und starken Winde beliebt ist. In der Tat gibt es sogar nepalesische Lieder, die Tribut an den starken Windsto\u00df zahlen, der in Jomsom um die Mittagszeit weht. Nach dem Erreichen von Jomsom k\u00f6nnen wir das \u00d6kologische Museum besuchen, das Informationen \u00fcber die reiche Kultur von Jomsom sowie die Flora und Fauna enth\u00e4lt, die im Tal geb\u00fcrtig sind. \u00dcbernachtung in Jomsom.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck Mittagessen Abendessen<\/p>\n<p><strong>Tag 16: Fliege von Jomsom nach Pokhara: 25 Minuten<\/strong><br \/>\n Heute fliegen wir mit dem fr\u00fchesten Flugzeug nach Pokhara der Seestadt. Nach dem Check-in in unserem Hotel k\u00f6nnen wir uns ausruhen oder das Seengebiet in der N\u00e4he des Fewa Sees besuchen. Hier k\u00f6nnen wir gern Souvenirs kaufen oder einige lokale Delikatessen probieren. \u00dcbernachtung in Pokhara.<br \/>\n Inbegriffene Mahlzeiten: Fr\u00fchst\u00fcck<\/p>\n<p><strong>Tag 17: Fahren Sie von Pokhara nach Kathmandu: 6 Stunden<\/strong><br \/>\n Nach dem Fr\u00fchst\u00fcck verabschieden wir uns von der wundersch\u00f6nen Seestadt Pokhara und fahren in Richtung Kathmandu. Nach dem Erreichen von Kathmandu haben wir den Rest des Tages frei. Es wird auch ein Abschiedsessen geben, das am Abend von Pinnacle Treks veranstaltet wird, um den erfolgreichen Abschluss unserer Reise zu feiern.<\/p>\n<\/div>\n<a id=\"opener-unter3\" class=\"opener\" href=\"javascript:mj_toggle_section('unter3')\">Preis inklusive\/exklusive<\/a>\n<div id='section-unter3' class='section clearfix'>\n<h4>Inkludierte Kosten:<\/h4>\n<ul>\n<li>Alle Flughafen- \/ Hoteltransfers mit einem privaten Fahrzeug<\/li>\n<li>Sightseeing in KTM valley<\/li>\n<li>Drei \u00dcbernachtungen in Kathmandu und Pokhara inkl. Fr\u00fchst\u00fcck<\/li>\n<li>Teeh\u00e4user \/ Lodge und Zelt Unterkunft w\u00e4hrend Trekking\u00a0<\/li>\n<li>Zelt Unterkunft w\u00e4hrend des Aufstiegs<\/li>\n<li>Alle Mahlzeiten (Fr\u00fchst\u00fcck, Mittagessen und Abendessen w\u00e4hrend Trekking und Kletterung<\/li>\n<li>Willkommens- und Abschiedsessen<\/li>\n<li>Alle Bodentransporte auf der Route durch Privatfahrzeuge\u00a0<\/li>\n<li>Inlandsflug von Jomsom nach Pokhara<\/li>\n<li>Englisch sprechender, geschulter und erfahrener Trekking-Guide, Kletter-Guide und Assistent Guide<\/li>\n<li>Sherpa Service (2 Trekker: 1 Sherpa)<\/li>\n<li>Personalkosten einschlie\u00dflich ihrer Geh\u00e4lter, Versicherung, Ausr\u00fcstung, Inland Flug, Essen und Unterkunft<\/li>\n<li>All necessary paperwork; trekking permits and Pisang Peak climbing permit<\/li>\n<li>Down jacket and sleeping bag (to be returned after trip completion)<\/li>\n<li>Pinnacle Trekking Sporttasche und Trekking-Karte<\/li>\n<li>All necessary paperwork; trekking permits and Pisang Peak climbing permit<\/li>\n<li>Good quality tents and kitchen utensils for camping<\/li>\n<li>Group mountaineering (climbing) equipments<\/li>\n<li>Medical kit (carried by your guide)<\/li>\n<\/ul>\n<h4>Nicht inkludierte Kosten:<\/h4>\n<ul>\n<li>Nepal Visumgeb\u00fchr (bitte zwei Passfotos und genaue USD in bar mitbringen)<\/li>\n<li>Internationaler Flug von und nach Kathmandu<\/li>\n<li>\u00dcbergep\u00e4ckgeb\u00fchren (wenn Sie mehr als 15 kg Gep\u00e4ck haben, ist die Ladungsgeb\u00fchr ca. $ 1,5 pro kg)<\/li>\n<li>Extra Nacht \u2013 Unterkunft in Kathmandu und\/oder Pokhara wegen der fr\u00fchen Ankunft, sp\u00e4ten Abreise, fr\u00fchere R\u00fcckkehr vom Berg (aus irgendeinem Grund) als die geplante Route<\/li>\n<li>H\u00f6henkammer (PAC) oder Sauerstoff<\/li>\n<li>Mittagessen und Abendessen in Kathmandu und Pokhara (und auch im Falle einer fr\u00fchen R\u00fcckkehr vom Berg als der geplanten Reiseroute)<\/li>\n<li>Reise- und Rettungsversicherung<\/li>\n<li>Pers\u00f6nliche Ausgaben (Telefongespr\u00e4che, W\u00e4sche, Barrechnungen, Akku-Aufladung, extra Sherpa, abgef\u00fclltes oder gekochtes Wasser, Dusche, Heizung usw.)<\/li>\n<li>Pers\u00f6nliche Kletterausr\u00fcstung<\/li>\n<li>Kletterf\u00fchrer auf Wunsch<\/li>\n<li>Optionale Ausfl\u00fcge und Besichtigungen, falls erweitert<\/li>\n<li>Trinkgeld f\u00fcr Guide und Sherpa<\/li>\n<\/ul>\n<\/div>\n<a id=\"opener-unter4\" class=\"opener\" href=\"javascript:mj_toggle_section('unter4')\">Warum Pinnacle Trek?<\/a>\n<div id='section-unter4' class='section clearfix'>\n<h3>Warum Sie Ihre Tour mit Pinnacle Trek buchen sollten:<\/h3>\n<ul>\n<li>Bester Preis mit bester Gastfreundschaft<\/li>\n<li>Sie haben eine gr\u00f6\u00dfere Gruppe? Wir k\u00f6nnen Ihnen gerne helfen!<\/li>\n<li>\u00d6rtlich erfahrene Guides und Sherpas<\/li>\n<li>Erstklassiger Kundendienst<\/li>\n<li>Lieferdatum ist garantiert<\/li>\n<li>Wir k\u00f6nnen Ihnen dabei helfen, Ihren Trek Ihrem Budget anzupassen<\/li>\n<li>Wir k\u00f6nnen die Reise nach Ihrem Bedarf\u00a0anpassen<\/li>\n<li>15 Jahre exzellente Trekkingerfahrung<\/li>\n<\/ul>\n<\/div>\n<a id=\"opener-unter5\" class=\"opener\" href=\"javascript:mj_toggle_section('unter5')\">Stornobedingungen<\/a>\n<div id='section-unter5' class='section clearfix'>\n<h3>Stornobedingungen<\/h3>\n<p>Wir verstehen, dass Dinge passieren und Pl\u00e4ne sich \u00e4ndern k\u00f6nnen. Wir erstatten Ihnen Ihre Kaution abz\u00fcglich einer Stornogeb\u00fchr von $ 170. Sobald wir Ihren Flug zwischen Jomsom nach Pokhara gebucht haben, ist Ihre Einzahlung nicht r\u00fcckzahlbar. Wenn Sie Ihre Reisedaten \u00e4ndern m\u00f6chten, k\u00f6nnen wir Sie in regelm\u00e4\u00dfigen Abst\u00e4nden umgehen, aber bitte mindestens 7 Tage vorher melden.\u00a0<\/p>\n<\/div>\n<\/p><input class=\"fooboxshare_post_id\" type=\"hidden\" value=\"310\"\/>","protected":false},"excerpt":{"rendered":"<p>Informationen zur Tour Die Pisang Gipfelbesteigung beinhaltet ein Trekking in der ber\u00fchmten Annapurna Region und dem Gipfel Pisang Peak. Dar\u00fcber hinaus besuchen wir Muktinath und wandern in der wundersch\u00f6nen Region Manang von Nepal. Unsere 18-t\u00e4gige Reise beginnt in Kathmandu, wo wir unsere Kletterguide \/ Guide und Mitkletterer treffen. Wir fahren am n\u00e4chsten Tag nach Dharapani [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":286,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peak"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pisang Gipfelbesteigung mit Thorong La Pass - Pinnacle Treks &amp; expedition - Adventure Trekking Nepal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pisang Gipfelbesteigung mit Thorong La Pass - Pinnacle Treks &amp; expedition - Adventure Trekking Nepal\" \/>\n<meta property=\"og:description\" content=\"Informationen zur Tour Die Pisang Gipfelbesteigung beinhaltet ein Trekking in der ber\u00fchmten Annapurna Region und dem Gipfel Pisang Peak. Dar\u00fcber hinaus besuchen wir Muktinath und wandern in der wundersch\u00f6nen Region Manang von Nepal. Unsere 18-t\u00e4gige Reise beginnt in Kathmandu, wo wir unsere Kletterguide \/ Guide und Mitkletterer treffen. Wir fahren am n\u00e4chsten Tag nach Dharapani [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/\" \/>\n<meta property=\"og:site_name\" content=\"Pinnacle Treks &amp; expedition - Adventure Trekking Nepal\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-28T09:43:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-07T05:06:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.adventuretrekking-nepal.com\/wp\/wp-content\/uploads\/pisang-peak.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rundr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rundr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"14\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/\"},\"author\":{\"name\":\"rundr\",\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/#\\\/schema\\\/person\\\/96c598b1bd0ecfe12e1de6af5f4e194c\"},\"headline\":\"Pisang Gipfelbesteigung mit Thorong La Pass\",\"datePublished\":\"2017-06-28T09:43:41+00:00\",\"dateModified\":\"2017-07-07T05:06:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/\"},\"wordCount\":2792,\"image\":{\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/wp\\\/wp-content\\\/uploads\\\/pisang-peak.jpg\",\"articleSection\":[\"Peak\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/\",\"url\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/\",\"name\":\"Pisang Gipfelbesteigung mit Thorong La Pass - Pinnacle Treks &amp; expedition - Adventure Trekking Nepal\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/wp\\\/wp-content\\\/uploads\\\/pisang-peak.jpg\",\"datePublished\":\"2017-06-28T09:43:41+00:00\",\"dateModified\":\"2017-07-07T05:06:49+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/#\\\/schema\\\/person\\\/96c598b1bd0ecfe12e1de6af5f4e194c\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/wp\\\/wp-content\\\/uploads\\\/pisang-peak.jpg\",\"contentUrl\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/wp\\\/wp-content\\\/uploads\\\/pisang-peak.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/pisang-peak-climbing-mit-thorong-la-pass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pisang Gipfelbesteigung mit Thorong La Pass\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/#website\",\"url\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/\",\"name\":\"Pinnacle Treks &amp; expedition - Adventure Trekking Nepal\",\"description\":\"Adventure Trekking Nepal - Annapurna, Dolpa, Everest Region, Langtang, Manaslu Region, Gipfelbesteigungen, Uppermustang trek - Pinnacle Treks &amp; expedition.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/#\\\/schema\\\/person\\\/96c598b1bd0ecfe12e1de6af5f4e194c\",\"name\":\"rundr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d72e87a31a0b401ee5af11b2cf3030bd01217a21c7cacd28b8b53e738758082?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d72e87a31a0b401ee5af11b2cf3030bd01217a21c7cacd28b8b53e738758082?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d72e87a31a0b401ee5af11b2cf3030bd01217a21c7cacd28b8b53e738758082?s=96&d=mm&r=g\",\"caption\":\"rundr\"},\"sameAs\":[\"https:\\\/\\\/www.rundrweb.com\"],\"url\":\"http:\\\/\\\/www.adventuretrekking-nepal.com\\\/de\\\/author\\\/rundr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pisang Gipfelbesteigung mit Thorong La Pass - Pinnacle Treks &amp; expedition - Adventure Trekking Nepal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/","og_locale":"de_DE","og_type":"article","og_title":"Pisang Gipfelbesteigung mit Thorong La Pass - Pinnacle Treks &amp; expedition - Adventure Trekking Nepal","og_description":"Informationen zur Tour Die Pisang Gipfelbesteigung beinhaltet ein Trekking in der ber\u00fchmten Annapurna Region und dem Gipfel Pisang Peak. Dar\u00fcber hinaus besuchen wir Muktinath und wandern in der wundersch\u00f6nen Region Manang von Nepal. Unsere 18-t\u00e4gige Reise beginnt in Kathmandu, wo wir unsere Kletterguide \/ Guide und Mitkletterer treffen. Wir fahren am n\u00e4chsten Tag nach Dharapani [&hellip;]","og_url":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/","og_site_name":"Pinnacle Treks &amp; expedition - Adventure Trekking Nepal","article_published_time":"2017-06-28T09:43:41+00:00","article_modified_time":"2017-07-07T05:06:49+00:00","og_image":[{"width":1000,"height":667,"url":"http:\/\/www.adventuretrekking-nepal.com\/wp\/wp-content\/uploads\/pisang-peak.jpg","type":"image\/jpeg"}],"author":"rundr","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"rundr","Gesch\u00e4tzte Lesezeit":"14\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/#article","isPartOf":{"@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/"},"author":{"name":"rundr","@id":"http:\/\/www.adventuretrekking-nepal.com\/#\/schema\/person\/96c598b1bd0ecfe12e1de6af5f4e194c"},"headline":"Pisang Gipfelbesteigung mit Thorong La Pass","datePublished":"2017-06-28T09:43:41+00:00","dateModified":"2017-07-07T05:06:49+00:00","mainEntityOfPage":{"@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/"},"wordCount":2792,"image":{"@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/#primaryimage"},"thumbnailUrl":"http:\/\/www.adventuretrekking-nepal.com\/wp\/wp-content\/uploads\/pisang-peak.jpg","articleSection":["Peak"],"inLanguage":"de"},{"@type":"WebPage","@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/","url":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/","name":"Pisang Gipfelbesteigung mit Thorong La Pass - Pinnacle Treks &amp; expedition - Adventure Trekking Nepal","isPartOf":{"@id":"http:\/\/www.adventuretrekking-nepal.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/#primaryimage"},"image":{"@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/#primaryimage"},"thumbnailUrl":"http:\/\/www.adventuretrekking-nepal.com\/wp\/wp-content\/uploads\/pisang-peak.jpg","datePublished":"2017-06-28T09:43:41+00:00","dateModified":"2017-07-07T05:06:49+00:00","author":{"@id":"http:\/\/www.adventuretrekking-nepal.com\/#\/schema\/person\/96c598b1bd0ecfe12e1de6af5f4e194c"},"breadcrumb":{"@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/#primaryimage","url":"http:\/\/www.adventuretrekking-nepal.com\/wp\/wp-content\/uploads\/pisang-peak.jpg","contentUrl":"http:\/\/www.adventuretrekking-nepal.com\/wp\/wp-content\/uploads\/pisang-peak.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"http:\/\/www.adventuretrekking-nepal.com\/pisang-peak-climbing-mit-thorong-la-pass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/www.adventuretrekking-nepal.com\/de\/"},{"@type":"ListItem","position":2,"name":"Pisang Gipfelbesteigung mit Thorong La Pass"}]},{"@type":"WebSite","@id":"http:\/\/www.adventuretrekking-nepal.com\/#website","url":"http:\/\/www.adventuretrekking-nepal.com\/","name":"Pinnacle Treks &amp; expedition - Adventure Trekking Nepal","description":"Adventure Trekking Nepal - Annapurna, Dolpa, Everest Region, Langtang, Manaslu Region, Gipfelbesteigungen, Uppermustang trek - Pinnacle Treks &amp; expedition.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.adventuretrekking-nepal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/www.adventuretrekking-nepal.com\/#\/schema\/person\/96c598b1bd0ecfe12e1de6af5f4e194c","name":"rundr","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3d72e87a31a0b401ee5af11b2cf3030bd01217a21c7cacd28b8b53e738758082?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3d72e87a31a0b401ee5af11b2cf3030bd01217a21c7cacd28b8b53e738758082?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d72e87a31a0b401ee5af11b2cf3030bd01217a21c7cacd28b8b53e738758082?s=96&d=mm&r=g","caption":"rundr"},"sameAs":["https:\/\/www.rundrweb.com"],"url":"http:\/\/www.adventuretrekking-nepal.com\/de\/author\/rundr\/"}]}},"_links":{"self":[{"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/posts\/310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/comments?post=310"}],"version-history":[{"count":10,"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/posts\/310\/revisions"}],"predecessor-version":[{"id":690,"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/posts\/310\/revisions\/690"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/media\/286"}],"wp:attachment":[{"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/media?parent=310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/categories?post=310"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.adventuretrekking-nepal.com\/de\/wp-json\/wp\/v2\/tags?post=310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}